{"id":131574,"date":"2024-12-10T10:26:46","date_gmt":"2024-12-10T10:26:46","guid":{"rendered":"https:\/\/reparlab.com\/toutes-les-reparations\/bsm-r09-00\/"},"modified":"2026-05-04T20:53:42","modified_gmt":"2026-05-04T20:53:42","slug":"bsm-r09-00","status":"publish","type":"reparations","link":"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/","title":{"rendered":"BSM R09-00"},"content":{"rendered":"","protected":false},"featured_media":124864,"parent":0,"template":"","meta":{"_acf_changed":false},"equipement":[806,198,232],"vehicule":[31,29],"class_list":["post-131574","reparations","type-reparations","status-publish","has-post-thumbnail","hentry","equipement-bsm","equipement-bsm-boitier-de-servitude-moteur","equipement-electronic-control-systems","vehicule-c3","vehicule-citroen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9paration BSM R09-00 pour C3, CITROEN<\/title>\n<meta name=\"description\" content=\"Reparlab gives your BSM R09-00 a second life! Discover our list of electronic repairs now.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9paration BSM R09-00 pour C3, CITROEN\" \/>\n<meta property=\"og:description\" content=\"Reparlab gives your BSM R09-00 a second life! Discover our list of electronic repairs now.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/\" \/>\n<meta property=\"og:site_name\" content=\"Reparlab by Faurecia Clarion\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T20:53:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reparlab.com\/wp-content\/uploads\/2024\/05\/BSM_R09-00_01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/en\\\/all-kind-of-repairs\\\/bsm-r09-00\\\/\",\"url\":\"https:\\\/\\\/reparlab.com\\\/en\\\/all-kind-of-repairs\\\/bsm-r09-00\\\/\",\"name\":\"R\u00e9paration BSM R09-00 pour C3, CITROEN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/en\\\/all-kind-of-repairs\\\/bsm-r09-00\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/en\\\/all-kind-of-repairs\\\/bsm-r09-00\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/BSM_R09-00_01.png\",\"datePublished\":\"2024-12-10T10:26:46+00:00\",\"dateModified\":\"2026-05-04T20:53:42+00:00\",\"description\":\"Reparlab gives your BSM R09-00 a second life! Discover our list of electronic repairs now.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/en\\\/all-kind-of-repairs\\\/bsm-r09-00\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/reparlab.com\\\/en\\\/all-kind-of-repairs\\\/bsm-r09-00\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/en\\\/all-kind-of-repairs\\\/bsm-r09-00\\\/#primaryimage\",\"url\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/BSM_R09-00_01.png\",\"contentUrl\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/BSM_R09-00_01.png\",\"width\":900,\"height\":620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/en\\\/all-kind-of-repairs\\\/bsm-r09-00\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/reparlab.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"all repairs\",\"item\":\"https:\\\/\\\/reparlab.com\\\/en\\\/all-kind-of-repairs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CITROEN\",\"item\":\"https:\\\/\\\/reparlab.com\\\/vehicule\\\/citroen\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"C3\",\"item\":\"https:\\\/\\\/reparlab.com\\\/vehicule\\\/citroen\\\/c3\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"BSM R09-00\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/reparlab.com\\\/en\\\/\",\"name\":\"Reparlab by Faurecia Clarion\",\"description\":\"Une seconde vie pour vos pi\u00e8ces \u00e9lectroniques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/reparlab.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9paration BSM R09-00 pour C3, CITROEN","description":"Reparlab gives your BSM R09-00 a second life! Discover our list of electronic repairs now.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/","og_locale":"en_US","og_type":"article","og_title":"R\u00e9paration BSM R09-00 pour C3, CITROEN","og_description":"Reparlab gives your BSM R09-00 a second life! Discover our list of electronic repairs now.","og_url":"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/","og_site_name":"Reparlab by Faurecia Clarion","article_modified_time":"2026-05-04T20:53:42+00:00","og_image":[{"width":900,"height":620,"url":"https:\/\/reparlab.com\/wp-content\/uploads\/2024\/05\/BSM_R09-00_01.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/","url":"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/","name":"R\u00e9paration BSM R09-00 pour C3, CITROEN","isPartOf":{"@id":"https:\/\/reparlab.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/#primaryimage"},"image":{"@id":"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/#primaryimage"},"thumbnailUrl":"https:\/\/reparlab.com\/wp-content\/uploads\/2024\/05\/BSM_R09-00_01.png","datePublished":"2024-12-10T10:26:46+00:00","dateModified":"2026-05-04T20:53:42+00:00","description":"Reparlab gives your BSM R09-00 a second life! Discover our list of electronic repairs now.","breadcrumb":{"@id":"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/#primaryimage","url":"https:\/\/reparlab.com\/wp-content\/uploads\/2024\/05\/BSM_R09-00_01.png","contentUrl":"https:\/\/reparlab.com\/wp-content\/uploads\/2024\/05\/BSM_R09-00_01.png","width":900,"height":620},{"@type":"BreadcrumbList","@id":"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/bsm-r09-00\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/reparlab.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"all repairs","item":"https:\/\/reparlab.com\/en\/all-kind-of-repairs\/"},{"@type":"ListItem","position":3,"name":"CITROEN","item":"https:\/\/reparlab.com\/vehicule\/citroen\/"},{"@type":"ListItem","position":4,"name":"C3","item":"https:\/\/reparlab.com\/vehicule\/citroen\/c3\/"},{"@type":"ListItem","position":5,"name":"BSM R09-00"}]},{"@type":"WebSite","@id":"https:\/\/reparlab.com\/en\/#website","url":"https:\/\/reparlab.com\/en\/","name":"Reparlab by Faurecia Clarion","description":"Une seconde vie pour vos pi\u00e8ces \u00e9lectroniques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reparlab.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/reparlab.com\/en\/wp-json\/wp\/v2\/reparations\/131574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reparlab.com\/en\/wp-json\/wp\/v2\/reparations"}],"about":[{"href":"https:\/\/reparlab.com\/en\/wp-json\/wp\/v2\/types\/reparations"}],"version-history":[{"count":1,"href":"https:\/\/reparlab.com\/en\/wp-json\/wp\/v2\/reparations\/131574\/revisions"}],"predecessor-version":[{"id":196791,"href":"https:\/\/reparlab.com\/en\/wp-json\/wp\/v2\/reparations\/131574\/revisions\/196791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reparlab.com\/en\/wp-json\/wp\/v2\/media\/124864"}],"wp:attachment":[{"href":"https:\/\/reparlab.com\/en\/wp-json\/wp\/v2\/media?parent=131574"}],"wp:term":[{"taxonomy":"equipement","embeddable":true,"href":"https:\/\/reparlab.com\/en\/wp-json\/wp\/v2\/equipement?post=131574"},{"taxonomy":"vehicule","embeddable":true,"href":"https:\/\/reparlab.com\/en\/wp-json\/wp\/v2\/vehicule?post=131574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}