{"id":179312,"date":"2024-12-10T10:11:58","date_gmt":"2024-12-10T10:11:58","guid":{"rendered":"https:\/\/reparlab.com\/toutes-les-reparations\/rd4-6\/"},"modified":"2026-05-04T14:06:41","modified_gmt":"2026-05-04T14:06:41","slug":"rd4-6","status":"publish","type":"reparations","link":"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/","title":{"rendered":"RD4"},"content":{"rendered":"","protected":false},"featured_media":118927,"parent":0,"template":"","meta":{"_acf_changed":false},"equipement":[273,872],"vehicule":[33,29],"class_list":["post-179312","reparations","type-reparations","status-publish","has-post-thumbnail","hentry","equipement-multimedia-y-navegacion","equipement-radio-cd-es","vehicule-c5","vehicule-citroen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9paration RD4 pour C5, CITROEN<\/title>\n<meta name=\"description\" content=\"Economisez avec Reparlab en r\u00e9parant le RD4 Continental de votre C5, CITROEN partout en Europe\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9paration RD4 pour C5, CITROEN\" \/>\n<meta property=\"og:description\" content=\"Economisez avec Reparlab en r\u00e9parant le RD4 Continental de votre C5, CITROEN partout en Europe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Reparlab by Faurecia Clarion\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T14:06:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/RD4_01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"286\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/es\\\/todas-nuestras-reparaciones\\\/rd4-6\\\/\",\"url\":\"https:\\\/\\\/reparlab.com\\\/es\\\/todas-nuestras-reparaciones\\\/rd4-6\\\/\",\"name\":\"R\u00e9paration RD4 pour C5, CITROEN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/es\\\/todas-nuestras-reparaciones\\\/rd4-6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/es\\\/todas-nuestras-reparaciones\\\/rd4-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/RD4_01.png\",\"datePublished\":\"2024-12-10T10:11:58+00:00\",\"dateModified\":\"2026-05-04T14:06:41+00:00\",\"description\":\"Economisez avec Reparlab en r\u00e9parant le RD4 Continental de votre C5, CITROEN partout en Europe\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/es\\\/todas-nuestras-reparaciones\\\/rd4-6\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/reparlab.com\\\/es\\\/todas-nuestras-reparaciones\\\/rd4-6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/es\\\/todas-nuestras-reparaciones\\\/rd4-6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/RD4_01.png\",\"contentUrl\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/RD4_01.png\",\"width\":900,\"height\":286},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/es\\\/todas-nuestras-reparaciones\\\/rd4-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/reparlab.com\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todas las reparaciones\",\"item\":\"https:\\\/\\\/reparlab.com\\\/es\\\/todas-nuestras-reparaciones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CITROEN\",\"item\":\"https:\\\/\\\/reparlab.com\\\/vehicule\\\/citroen\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"C5\",\"item\":\"https:\\\/\\\/reparlab.com\\\/vehicule\\\/citroen\\\/c5\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"RD4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/reparlab.com\\\/es\\\/\",\"name\":\"Reparlab by Faurecia Clarion\",\"description\":\"Une seconde vie pour vos pi\u00e8ces \u00e9lectroniques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/reparlab.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9paration RD4 pour C5, CITROEN","description":"Economisez avec Reparlab en r\u00e9parant le RD4 Continental de votre C5, CITROEN partout en Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/","og_locale":"es_ES","og_type":"article","og_title":"R\u00e9paration RD4 pour C5, CITROEN","og_description":"Economisez avec Reparlab en r\u00e9parant le RD4 Continental de votre C5, CITROEN partout en Europe","og_url":"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/","og_site_name":"Reparlab by Faurecia Clarion","article_modified_time":"2026-05-04T14:06:41+00:00","og_image":[{"width":900,"height":286,"url":"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/RD4_01.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/","url":"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/","name":"R\u00e9paration RD4 pour C5, CITROEN","isPartOf":{"@id":"https:\/\/reparlab.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/#primaryimage"},"image":{"@id":"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/#primaryimage"},"thumbnailUrl":"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/RD4_01.png","datePublished":"2024-12-10T10:11:58+00:00","dateModified":"2026-05-04T14:06:41+00:00","description":"Economisez avec Reparlab en r\u00e9parant le RD4 Continental de votre C5, CITROEN partout en Europe","breadcrumb":{"@id":"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/#primaryimage","url":"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/RD4_01.png","contentUrl":"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/RD4_01.png","width":900,"height":286},{"@type":"BreadcrumbList","@id":"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/rd4-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/reparlab.com\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"Todas las reparaciones","item":"https:\/\/reparlab.com\/es\/todas-nuestras-reparaciones\/"},{"@type":"ListItem","position":3,"name":"CITROEN","item":"https:\/\/reparlab.com\/vehicule\/citroen\/"},{"@type":"ListItem","position":4,"name":"C5","item":"https:\/\/reparlab.com\/vehicule\/citroen\/c5\/"},{"@type":"ListItem","position":5,"name":"RD4"}]},{"@type":"WebSite","@id":"https:\/\/reparlab.com\/es\/#website","url":"https:\/\/reparlab.com\/es\/","name":"Reparlab by Faurecia Clarion","description":"Une seconde vie pour vos pi\u00e8ces \u00e9lectroniques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reparlab.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/reparlab.com\/es\/wp-json\/wp\/v2\/reparations\/179312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reparlab.com\/es\/wp-json\/wp\/v2\/reparations"}],"about":[{"href":"https:\/\/reparlab.com\/es\/wp-json\/wp\/v2\/types\/reparations"}],"version-history":[{"count":1,"href":"https:\/\/reparlab.com\/es\/wp-json\/wp\/v2\/reparations\/179312\/revisions"}],"predecessor-version":[{"id":220355,"href":"https:\/\/reparlab.com\/es\/wp-json\/wp\/v2\/reparations\/179312\/revisions\/220355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reparlab.com\/es\/wp-json\/wp\/v2\/media\/118927"}],"wp:attachment":[{"href":"https:\/\/reparlab.com\/es\/wp-json\/wp\/v2\/media?parent=179312"}],"wp:term":[{"taxonomy":"equipement","embeddable":true,"href":"https:\/\/reparlab.com\/es\/wp-json\/wp\/v2\/equipement?post=179312"},{"taxonomy":"vehicule","embeddable":true,"href":"https:\/\/reparlab.com\/es\/wp-json\/wp\/v2\/vehicule?post=179312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}