{"id":147273,"date":"2024-12-10T10:19:48","date_gmt":"2024-12-10T10:19:48","guid":{"rendered":"https:\/\/reparlab.com\/toutes-les-reparations\/25915-4nr0e\/"},"modified":"2026-07-23T15:13:43","modified_gmt":"2026-07-23T15:13:43","slug":"25915-4nr0e","status":"publish","type":"reparations","link":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/","title":{"rendered":"QY8202NE"},"content":{"rendered":"","protected":false},"featured_media":122184,"parent":0,"template":"","meta":{"_acf_changed":false},"equipement":[233,878],"vehicule":[291,134],"class_list":["post-147273","reparations","type-reparations","status-publish","has-post-thumbnail","hentry","equipement-multimedia-en-navigatie","equipement-navigatiesysteem","vehicule-leaf","vehicule-nissan"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9paration QY8202NE pour LEAF, NISSAN<\/title>\n<meta name=\"description\" content=\"Economisez avec Reparlab en r\u00e9parant le QY8202NE Clarion de votre LEAF, NISSAN partout en Europe\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9paration QY8202NE pour LEAF, NISSAN\" \/>\n<meta property=\"og:description\" content=\"Economisez avec Reparlab en r\u00e9parant le QY8202NE Clarion de votre LEAF, NISSAN partout en Europe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/\" \/>\n<meta property=\"og:site_name\" content=\"Reparlab by Faurecia Clarion\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-23T15:13:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/QY8202NE_01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"547\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-4nr0e\\\/\",\"url\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-4nr0e\\\/\",\"name\":\"R\u00e9paration QY8202NE pour LEAF, NISSAN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-4nr0e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-4nr0e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/QY8202NE_01.png\",\"datePublished\":\"2024-12-10T10:19:48+00:00\",\"dateModified\":\"2026-07-23T15:13:43+00:00\",\"description\":\"Economisez avec Reparlab en r\u00e9parant le QY8202NE Clarion de votre LEAF, NISSAN partout en Europe\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-4nr0e\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-4nr0e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-4nr0e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/QY8202NE_01.png\",\"contentUrl\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/QY8202NE_01.png\",\"width\":900,\"height\":547},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-4nr0e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alle soorten reparaties\",\"item\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NISSAN\",\"item\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/vehicule\\\/nissan\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"LEAF\",\"item\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/vehicule\\\/nissan\\\/leaf\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"QY8202NE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/\",\"name\":\"Reparlab by Faurecia Clarion\",\"description\":\"Une seconde vie pour vos pi\u00e8ces \u00e9lectroniques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9paration QY8202NE pour LEAF, NISSAN","description":"Economisez avec Reparlab en r\u00e9parant le QY8202NE Clarion de votre LEAF, NISSAN partout en Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/","og_locale":"nl_NL","og_type":"article","og_title":"R\u00e9paration QY8202NE pour LEAF, NISSAN","og_description":"Economisez avec Reparlab en r\u00e9parant le QY8202NE Clarion de votre LEAF, NISSAN partout en Europe","og_url":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/","og_site_name":"Reparlab by Faurecia Clarion","article_modified_time":"2026-07-23T15:13:43+00:00","og_image":[{"width":900,"height":547,"url":"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/QY8202NE_01.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/","url":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/","name":"R\u00e9paration QY8202NE pour LEAF, NISSAN","isPartOf":{"@id":"https:\/\/reparlab.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/#primaryimage"},"image":{"@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/#primaryimage"},"thumbnailUrl":"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/QY8202NE_01.png","datePublished":"2024-12-10T10:19:48+00:00","dateModified":"2026-07-23T15:13:43+00:00","description":"Economisez avec Reparlab en r\u00e9parant le QY8202NE Clarion de votre LEAF, NISSAN partout en Europe","breadcrumb":{"@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/#primaryimage","url":"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/QY8202NE_01.png","contentUrl":"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/QY8202NE_01.png","width":900,"height":547},{"@type":"BreadcrumbList","@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-4nr0e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/reparlab.com\/nl\/home\/"},{"@type":"ListItem","position":2,"name":"Alle soorten reparaties","item":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/"},{"@type":"ListItem","position":3,"name":"NISSAN","item":"https:\/\/reparlab.com\/nl\/vehicule\/nissan\/"},{"@type":"ListItem","position":4,"name":"LEAF","item":"https:\/\/reparlab.com\/nl\/vehicule\/nissan\/leaf\/"},{"@type":"ListItem","position":5,"name":"QY8202NE"}]},{"@type":"WebSite","@id":"https:\/\/reparlab.com\/nl\/#website","url":"https:\/\/reparlab.com\/nl\/","name":"Reparlab by Faurecia Clarion","description":"Une seconde vie pour vos pi\u00e8ces \u00e9lectroniques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reparlab.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/reparations\/147273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/reparations"}],"about":[{"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/types\/reparations"}],"version-history":[{"count":2,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/reparations\/147273\/revisions"}],"predecessor-version":[{"id":232941,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/reparations\/147273\/revisions\/232941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/media\/122184"}],"wp:attachment":[{"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/media?parent=147273"}],"wp:term":[{"taxonomy":"equipement","embeddable":true,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/equipement?post=147273"},{"taxonomy":"vehicule","embeddable":true,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/vehicule?post=147273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}