{"id":148539,"date":"2024-12-10T10:23:39","date_gmt":"2024-12-10T10:23:39","guid":{"rendered":"https:\/\/reparlab.com\/toutes-les-reparations\/25915-6hs6a\/"},"modified":"2026-07-23T17:06:43","modified_gmt":"2026-07-23T17:06:43","slug":"25915-6hs6a","status":"publish","type":"reparations","link":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/","title":{"rendered":"QY8352PI"},"content":{"rendered":"","protected":false},"featured_media":122182,"parent":0,"template":"","meta":{"_acf_changed":false},"equipement":[233,878],"vehicule":[137,134],"class_list":["post-148539","reparations","type-reparations","status-publish","has-post-thumbnail","hentry","equipement-multimedia-en-navigatie","equipement-navigatiesysteem","vehicule-gt-r","vehicule-nissan"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9paration QY8352PI pour GT-R, NISSAN<\/title>\n<meta name=\"description\" content=\"Economisez avec Reparlab en r\u00e9parant le QY8352PI Clarion de votre GT-R, NISSAN partout en Europe\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9paration QY8352PI pour GT-R, NISSAN\" \/>\n<meta property=\"og:description\" content=\"Economisez avec Reparlab en r\u00e9parant le QY8352PI Clarion de votre GT-R, NISSAN partout en Europe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/\" \/>\n<meta property=\"og:site_name\" content=\"Reparlab by Faurecia Clarion\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-23T17:06:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/QY8352NA_01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-6hs6a\\\/\",\"url\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-6hs6a\\\/\",\"name\":\"R\u00e9paration QY8352PI pour GT-R, NISSAN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-6hs6a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-6hs6a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/QY8352NA_01.png\",\"datePublished\":\"2024-12-10T10:23:39+00:00\",\"dateModified\":\"2026-07-23T17:06:43+00:00\",\"description\":\"Economisez avec Reparlab en r\u00e9parant le QY8352PI Clarion de votre GT-R, NISSAN partout en Europe\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-6hs6a\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-6hs6a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-6hs6a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/QY8352NA_01.png\",\"contentUrl\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/QY8352NA_01.png\",\"width\":900,\"height\":514},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/25915-6hs6a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alle soorten reparaties\",\"item\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NISSAN\",\"item\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/vehicule\\\/nissan\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"GT-R\",\"item\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/vehicule\\\/nissan\\\/gt-r\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"QY8352PI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/\",\"name\":\"Reparlab by Faurecia Clarion\",\"description\":\"Une seconde vie pour vos pi\u00e8ces \u00e9lectroniques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9paration QY8352PI pour GT-R, NISSAN","description":"Economisez avec Reparlab en r\u00e9parant le QY8352PI Clarion de votre GT-R, NISSAN partout en Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/","og_locale":"nl_NL","og_type":"article","og_title":"R\u00e9paration QY8352PI pour GT-R, NISSAN","og_description":"Economisez avec Reparlab en r\u00e9parant le QY8352PI Clarion de votre GT-R, NISSAN partout en Europe","og_url":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/","og_site_name":"Reparlab by Faurecia Clarion","article_modified_time":"2026-07-23T17:06:43+00:00","og_image":[{"width":900,"height":514,"url":"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/QY8352NA_01.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/","url":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/","name":"R\u00e9paration QY8352PI pour GT-R, NISSAN","isPartOf":{"@id":"https:\/\/reparlab.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/#primaryimage"},"image":{"@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/#primaryimage"},"thumbnailUrl":"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/QY8352NA_01.png","datePublished":"2024-12-10T10:23:39+00:00","dateModified":"2026-07-23T17:06:43+00:00","description":"Economisez avec Reparlab en r\u00e9parant le QY8352PI Clarion de votre GT-R, NISSAN partout en Europe","breadcrumb":{"@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/#primaryimage","url":"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/QY8352NA_01.png","contentUrl":"https:\/\/reparlab.com\/wp-content\/uploads\/2018\/08\/QY8352NA_01.png","width":900,"height":514},{"@type":"BreadcrumbList","@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/25915-6hs6a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/reparlab.com\/nl\/home\/"},{"@type":"ListItem","position":2,"name":"Alle soorten reparaties","item":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/"},{"@type":"ListItem","position":3,"name":"NISSAN","item":"https:\/\/reparlab.com\/nl\/vehicule\/nissan\/"},{"@type":"ListItem","position":4,"name":"GT-R","item":"https:\/\/reparlab.com\/nl\/vehicule\/nissan\/gt-r\/"},{"@type":"ListItem","position":5,"name":"QY8352PI"}]},{"@type":"WebSite","@id":"https:\/\/reparlab.com\/nl\/#website","url":"https:\/\/reparlab.com\/nl\/","name":"Reparlab by Faurecia Clarion","description":"Une seconde vie pour vos pi\u00e8ces \u00e9lectroniques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reparlab.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/reparations\/148539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/reparations"}],"about":[{"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/types\/reparations"}],"version-history":[{"count":2,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/reparations\/148539\/revisions"}],"predecessor-version":[{"id":233486,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/reparations\/148539\/revisions\/233486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/media\/122182"}],"wp:attachment":[{"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/media?parent=148539"}],"wp:term":[{"taxonomy":"equipement","embeddable":true,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/equipement?post=148539"},{"taxonomy":"vehicule","embeddable":true,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/vehicule?post=148539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}