{"id":150254,"date":"2024-12-10T10:28:32","date_gmt":"2024-12-10T10:28:32","guid":{"rendered":"https:\/\/reparlab.com\/toutes-les-reparations\/abs-xc60\/"},"modified":"2026-05-04T22:06:25","modified_gmt":"2026-05-04T22:06:25","slug":"abs-xc60","status":"publish","type":"reparations","link":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/","title":{"rendered":"ABS XC60"},"content":{"rendered":"","protected":false},"featured_media":242424,"parent":0,"template":"","meta":{"_acf_changed":false},"equipement":[918,229],"vehicule":[782,796],"class_list":["post-150254","reparations","type-reparations","status-publish","has-post-thumbnail","hentry","equipement-abs-nl","equipement-actieve-veiligheidssystemen","vehicule-volvo","vehicule-xc60"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00e9paration ABS XC60 pour VOLVO, XC60<\/title>\n<meta name=\"description\" content=\"Economisez avec Reparlab en r\u00e9parant le ABS XC60 de votre VOLVO, XC60 partout en Europe\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9paration ABS XC60 pour VOLVO, XC60\" \/>\n<meta property=\"og:description\" content=\"Economisez avec Reparlab en r\u00e9parant le ABS XC60 de votre VOLVO, XC60 partout en Europe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/\" \/>\n<meta property=\"og:site_name\" content=\"Reparlab by Faurecia Clarion\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T22:06:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reparlab.com\/wp-content\/uploads\/2026\/02\/picto_abs_01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/abs-xc60\\\/\",\"url\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/abs-xc60\\\/\",\"name\":\"R\u00e9paration ABS XC60 pour VOLVO, XC60\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/abs-xc60\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/abs-xc60\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/picto_abs_01.png\",\"datePublished\":\"2024-12-10T10:28:32+00:00\",\"dateModified\":\"2026-05-04T22:06:25+00:00\",\"description\":\"Economisez avec Reparlab en r\u00e9parant le ABS XC60 de votre VOLVO, XC60 partout en Europe\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/abs-xc60\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/abs-xc60\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/abs-xc60\\\/#primaryimage\",\"url\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/picto_abs_01.png\",\"contentUrl\":\"https:\\\/\\\/reparlab.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/picto_abs_01.png\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/abs-xc60\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startpagina\",\"item\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alle soorten reparaties\",\"item\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/alle-soorten-reparaties\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"VOLVO\",\"item\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/vehicule\\\/volvo\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"XC60\",\"item\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/vehicule\\\/volvo\\\/xc60\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"ABS XC60\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/\",\"name\":\"Reparlab by Faurecia Clarion\",\"description\":\"Une seconde vie pour vos pi\u00e8ces \u00e9lectroniques\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/reparlab.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9paration ABS XC60 pour VOLVO, XC60","description":"Economisez avec Reparlab en r\u00e9parant le ABS XC60 de votre VOLVO, XC60 partout en Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/","og_locale":"nl_NL","og_type":"article","og_title":"R\u00e9paration ABS XC60 pour VOLVO, XC60","og_description":"Economisez avec Reparlab en r\u00e9parant le ABS XC60 de votre VOLVO, XC60 partout en Europe","og_url":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/","og_site_name":"Reparlab by Faurecia Clarion","article_modified_time":"2026-05-04T22:06:25+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/reparlab.com\/wp-content\/uploads\/2026\/02\/picto_abs_01.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/","url":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/","name":"R\u00e9paration ABS XC60 pour VOLVO, XC60","isPartOf":{"@id":"https:\/\/reparlab.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/#primaryimage"},"image":{"@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/#primaryimage"},"thumbnailUrl":"https:\/\/reparlab.com\/wp-content\/uploads\/2026\/02\/picto_abs_01.png","datePublished":"2024-12-10T10:28:32+00:00","dateModified":"2026-05-04T22:06:25+00:00","description":"Economisez avec Reparlab en r\u00e9parant le ABS XC60 de votre VOLVO, XC60 partout en Europe","breadcrumb":{"@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/#primaryimage","url":"https:\/\/reparlab.com\/wp-content\/uploads\/2026\/02\/picto_abs_01.png","contentUrl":"https:\/\/reparlab.com\/wp-content\/uploads\/2026\/02\/picto_abs_01.png","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/abs-xc60\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startpagina","item":"https:\/\/reparlab.com\/nl\/home\/"},{"@type":"ListItem","position":2,"name":"Alle soorten reparaties","item":"https:\/\/reparlab.com\/nl\/alle-soorten-reparaties\/"},{"@type":"ListItem","position":3,"name":"VOLVO","item":"https:\/\/reparlab.com\/nl\/vehicule\/volvo\/"},{"@type":"ListItem","position":4,"name":"XC60","item":"https:\/\/reparlab.com\/nl\/vehicule\/volvo\/xc60\/"},{"@type":"ListItem","position":5,"name":"ABS XC60"}]},{"@type":"WebSite","@id":"https:\/\/reparlab.com\/nl\/#website","url":"https:\/\/reparlab.com\/nl\/","name":"Reparlab by Faurecia Clarion","description":"Une seconde vie pour vos pi\u00e8ces \u00e9lectroniques","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reparlab.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/reparations\/150254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/reparations"}],"about":[{"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/types\/reparations"}],"version-history":[{"count":1,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/reparations\/150254\/revisions"}],"predecessor-version":[{"id":203120,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/reparations\/150254\/revisions\/203120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/media\/242424"}],"wp:attachment":[{"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/media?parent=150254"}],"wp:term":[{"taxonomy":"equipement","embeddable":true,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/equipement?post=150254"},{"taxonomy":"vehicule","embeddable":true,"href":"https:\/\/reparlab.com\/nl\/wp-json\/wp\/v2\/vehicule?post=150254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}